{"id":3196,"date":"2020-04-29T13:55:49","date_gmt":"2020-04-29T13:55:49","guid":{"rendered":"http:\/\/arrastao.org.br\/?p=3196"},"modified":"2022-06-14T14:25:42","modified_gmt":"2022-06-14T17:25:42","slug":"3-738-cestas-basicas-entregues-ate-o-momento-gracas-ao-poder-da-doacao","status":"publish","type":"post","link":"https:\/\/arrastao.org.br\/site\/3-738-cestas-basicas-entregues-ate-o-momento-gracas-ao-poder-da-doacao\/","title":{"rendered":"3.738 cestas b\u00e1sicas entregues at\u00e9 o momento gra\u00e7as ao poder da doa\u00e7\u00e3o"},"content":{"rendered":"<h2 style=\"text-align: justify;\">Iniciamos uma campanha de arrecada\u00e7\u00e3o de cestas b\u00e1sicas que tem feito a diferen\u00e7a na vida de diversas fam\u00edlias do Campo Limpo em tempos de combate ao novo coronav\u00edrus.<\/h2>\n<figure id=\"attachment_3197\" aria-describedby=\"caption-attachment-3197\" style=\"width: 1024px\" class=\"wp-caption alignnone\"><img fetchpriority=\"high\" decoding=\"async\" class=\"size-full wp-image-3197\" src=\"http:\/\/arrastao.org.br\/site\/wp-content\/uploads\/2020\/04\/baixa-22042020-IMG_0105.jpg\" alt=\"Foto: Allan Reis\" width=\"1024\" height=\"683\" data-id=\"3197\"><figcaption id=\"caption-attachment-3197\" class=\"wp-caption-text\">Foto: Allan Reis<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Logo que iniciaram as primeiras not\u00edcias da chegada da COVID-19 ao Brasil, o Projeto Arrast\u00e3o come\u00e7ou a pensar nas poss\u00edveis estrat\u00e9gias para garantir o apoio \u00e0s fam\u00edlias atendidas por nossa organiza\u00e7\u00e3o. Com a suspens\u00e3o de atividades presenciais, uma necessidade se mostrou urgente: garantir a alimenta\u00e7\u00e3o de nossos educandos. Por isso, iniciamos uma campanha de arrecada\u00e7\u00e3o de cestas b\u00e1sicas para que as fam\u00edlias do Campo Limpo possam ter a alimenta\u00e7\u00e3o assegurada neste per\u00edodo.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Com a suspens\u00e3o das atividades nas escolas e organiza\u00e7\u00f5es sociais, as crian\u00e7as que antes se alimentavam nestas institui\u00e7\u00f5es, est\u00e3o realizando suas refei\u00e7\u00f5es em casa. Isso tem feito com que os custos familiares com alimenta\u00e7\u00e3o aumentem consideravelmente. No cen\u00e1rio atual, isto \u00e9 agravado pelo fato de que os respons\u00e1veis por suas fam\u00edlias n\u00e3o est\u00e3o saindo para trabalhar ou perderam seus empregos em decorr\u00eancia das atitudes necess\u00e1rias para conten\u00e7\u00e3o do v\u00edrus.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Em um dia normal de atividades no Projeto Arrast\u00e3o, os educandos t\u00eam suas refei\u00e7\u00f5es asseguradas nos refeit\u00f3rios de nossa institui\u00e7\u00e3o. No turno da manh\u00e3, crian\u00e7as e jovens recebem caf\u00e9 da manh\u00e3 e almo\u00e7o e no per\u00edodo vespertino, almo\u00e7o e lanche da tarde. Em atividades integrais da Educa\u00e7\u00e3o Infantil s\u00e3o servidas diariamente 5 refei\u00e7\u00f5es. Foram mais de 400 mil refei\u00e7\u00f5es servidas ao longo de 2019.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Neste momento, as refei\u00e7\u00f5es de nossos educandos t\u00eam sido garantidas atrav\u00e9s das cestas b\u00e1sicas que chegaram a nossa institui\u00e7\u00e3o por meio de doa\u00e7\u00f5es feitas por pessoas e empresas atrav\u00e9s do site <a href=\"http:\/\/www.doe.arrastao.org.br\">www.doe.arrastao.org.br<\/a>, entregues diretamente em nossa sede ou atrav\u00e9s de doa\u00e7\u00f5es feitas por meio de dep\u00f3sito na seguinte conta:<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Bradesco (237)<\/p>\n<p style=\"text-align: justify;\">Ag\u00eancia 1449<\/p>\n<p style=\"text-align: justify;\">Conta Corrente 41200-7<\/p>\n<p style=\"text-align: justify;\">Arrast\u00e3o Movimento de Promo\u00e7\u00e3o Humana<\/p>\n<p style=\"text-align: justify;\">CNPJ 43.082.197\/0001-68<\/p>\n<p style=\"text-align: justify;\">Enviar comprovante para <a href=\"mailto:doacao@arrastao.org.br\">doacao@arrastao.org.br<\/a><\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">At\u00e9 o momento, conseguimos garantir para as fam\u00edlias dos atendidos cestas b\u00e1sicas para os pr\u00f3ximos 3 meses. Tamb\u00e9m ampliamos a distribui\u00e7\u00e3o de cestas para outras fam\u00edlias da comunidade e demais organiza\u00e7\u00f5es do Campo Limpo que desenvolvem trabalhos de assist\u00eancia \u00e0 popula\u00e7\u00e3o da regi\u00e3o. Tudo isso gra\u00e7as ao poder da doa\u00e7\u00e3o e ao compromisso que firmamos h\u00e1 mais de 50 anos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Iniciamos uma campanha de arrecada\u00e7\u00e3o de cestas b\u00e1sicas que tem feito a diferen\u00e7a na vida de diversas fam\u00edlias do Campo Limpo em tempos de combate ao novo coronav\u00edrus. Logo que<\/p>\n","protected":false},"author":4,"featured_media":16332,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[33],"tags":[147,219],"class_list":["post-3196","post","type-post","status-publish","format-standard","has-post-thumbnail","category-noticias","tag-acao-social","tag-covid-19"],"_links":{"self":[{"href":"https:\/\/arrastao.org.br\/site\/wp-json\/wp\/v2\/posts\/3196","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/arrastao.org.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/arrastao.org.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/arrastao.org.br\/site\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/arrastao.org.br\/site\/wp-json\/wp\/v2\/comments?post=3196"}],"version-history":[{"count":1,"href":"https:\/\/arrastao.org.br\/site\/wp-json\/wp\/v2\/posts\/3196\/revisions"}],"predecessor-version":[{"id":16334,"href":"https:\/\/arrastao.org.br\/site\/wp-json\/wp\/v2\/posts\/3196\/revisions\/16334"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/arrastao.org.br\/site\/wp-json\/wp\/v2\/media\/16332"}],"wp:attachment":[{"href":"https:\/\/arrastao.org.br\/site\/wp-json\/wp\/v2\/media?parent=3196"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/arrastao.org.br\/site\/wp-json\/wp\/v2\/categories?post=3196"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/arrastao.org.br\/site\/wp-json\/wp\/v2\/tags?post=3196"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}